{"id":11707,"date":"2026-09-01T14:37:52","date_gmt":"2026-09-01T19:37:52","guid":{"rendered":"https:\/\/www.ana.gob.pa\/?p=11707"},"modified":"2026-09-01T14:37:53","modified_gmt":"2026-09-01T19:37:53","slug":"aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa","status":"publish","type":"post","link":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/","title":{"rendered":"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Inspectores de la Direcci\u00f3n de Prevenci\u00f3n y Fiscalizaci\u00f3n Aduanera (DPFA) lograron la retenci\u00f3n de material explosivo que era transportado de manera irregular en un veh\u00edculo particular, durante labores de verificaci\u00f3n e inspecci\u00f3n efectuadas en un punto de control de divisas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La acci\u00f3n se desarroll\u00f3 como parte de los esfuerzos permanentes de fiscalizaci\u00f3n y vigilancia que mantienen las autoridades aduaneras para garantizar el cumplimiento de las normativas vigentes en el territorio nacional. Durante la inspecci\u00f3n, los inspectores detectaron que el veh\u00edculo transportaba ocho cajas peque\u00f1as que conten\u00edan material explosivo tipo bengala, com\u00fanmente utilizado para actividades de pesca.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1086\" height=\"1364\" src=\"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/09\/IMG-20260901-WA0052_edit_222225731200630.jpg\" alt=\"\" class=\"wp-image-11709\" style=\"aspect-ratio:0.7962061957258114;width:326px;height:auto\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"808\" height=\"760\" src=\"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/09\/IMG-20260829-WA0010_edit_222265502932094.jpg\" alt=\"\" class=\"wp-image-11708\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el conteo correspondiente, se determin\u00f3 que la mercanc\u00eda consist\u00eda en un total de 800 unidades, con un valor aproximado de B\/. 12,000.00.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con las verificaciones realizadas por los inspectores, el responsable del transporte no contaba con la documentaci\u00f3n requerida para el traslado de material pirot\u00e9cnico o explosivo, ni con los permisos, requisitos institucionales y operativos obligatorios para el manejo y movilizaci\u00f3n de este tipo de productos dentro del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la presunta infracci\u00f3n a las disposiciones legales vigentes, la mercanc\u00eda fue retenida y puesta bajo custodia de la Autoridad Nacional de Aduanas, quedando a cargo del Departamento Sumarial, instancia que continuar\u00e1 con las investigaciones correspondientes para determinar las responsabilidades que resulten de este caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inspectores de la Direcci\u00f3n de Prevenci\u00f3n y Fiscalizaci\u00f3n Aduanera (DPFA) lograron la retenci\u00f3n de material explosivo que era transportado de manera irregular en un veh\u00edculo particular, durante labores de verificaci\u00f3n e inspecci\u00f3n efectuadas en un punto de control de divisas. La acci\u00f3n se desarroll\u00f3 como parte de los esfuerzos permanentes de fiscalizaci\u00f3n y vigilancia que [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":11710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[5],"tags":[],"class_list":["post-11707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa - Autoridad Nacional de Aduanas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa - Autoridad Nacional de Aduanas\" \/>\n<meta property=\"og:description\" content=\"Inspectores de la Direcci\u00f3n de Prevenci\u00f3n y Fiscalizaci\u00f3n Aduanera (DPFA) lograron la retenci\u00f3n de material explosivo que era transportado de manera irregular en un veh\u00edculo particular, durante labores de verificaci\u00f3n e inspecci\u00f3n efectuadas en un punto de control de divisas. La acci\u00f3n se desarroll\u00f3 como parte de los esfuerzos permanentes de fiscalizaci\u00f3n y vigilancia que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/\" \/>\n<meta property=\"og:site_name\" content=\"Autoridad Nacional de Aduanas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aduanas.panama\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T19:37:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T19:37:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/09\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ovidio Gomez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aduanaspanama\" \/>\n<meta name=\"twitter:site\" content=\"@aduanaspanama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ovidio Gomez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/\"},\"author\":{\"name\":\"Ovidio Gomez\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#\\\/schema\\\/person\\\/739397fec31e88f1da6069ed31320a02\"},\"headline\":\"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa\",\"datePublished\":\"2026-09-01T19:37:52+00:00\",\"dateModified\":\"2026-09-01T19:37:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/\"},\"wordCount\":246,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png\",\"articleSection\":[\"Ultimas Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/\",\"name\":\"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa - Autoridad Nacional de Aduanas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png\",\"datePublished\":\"2026-09-01T19:37:52+00:00\",\"dateModified\":\"2026-09-01T19:37:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png\",\"contentUrl\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png\",\"width\":1672,\"height\":941},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/09\\\/01\\\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ana.gob.pa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#website\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/\",\"name\":\"Autoridad Nacional de Aduanas\",\"description\":\"Autoridad Nacional de Aduanas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#organization\"},\"alternateName\":\"Autoridad Nacional de Aduanas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ana.gob.pa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#organization\",\"name\":\"Autoridad Nacional de Aduanas\",\"alternateName\":\"Autoridad Nacional de Aduanas\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-de-aduanas-y-gobierno.png\",\"contentUrl\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-de-aduanas-y-gobierno.png\",\"width\":2860,\"height\":423,\"caption\":\"Autoridad Nacional de Aduanas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aduanas.panama\\\/\",\"https:\\\/\\\/x.com\\\/aduanaspanama\",\"https:\\\/\\\/www.instagram.com\\\/aduanaspanama\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#\\\/schema\\\/person\\\/739397fec31e88f1da6069ed31320a02\",\"name\":\"Ovidio Gomez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g\",\"caption\":\"Ovidio Gomez\"},\"sameAs\":[\"https:\\\/\\\/www.ana.gob.pa\\\/w_ana\\\/\"],\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/author\\\/ogomez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa - Autoridad Nacional de Aduanas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/","og_locale":"es_ES","og_type":"article","og_title":"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa - Autoridad Nacional de Aduanas","og_description":"Inspectores de la Direcci\u00f3n de Prevenci\u00f3n y Fiscalizaci\u00f3n Aduanera (DPFA) lograron la retenci\u00f3n de material explosivo que era transportado de manera irregular en un veh\u00edculo particular, durante labores de verificaci\u00f3n e inspecci\u00f3n efectuadas en un punto de control de divisas. La acci\u00f3n se desarroll\u00f3 como parte de los esfuerzos permanentes de fiscalizaci\u00f3n y vigilancia que [&hellip;]","og_url":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/","og_site_name":"Autoridad Nacional de Aduanas","article_publisher":"https:\/\/www.facebook.com\/aduanas.panama\/","article_published_time":"2026-09-01T19:37:52+00:00","article_modified_time":"2026-09-01T19:37:53+00:00","og_image":[{"url":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/09\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png","width":800,"height":450,"type":"image\/png"}],"author":"Ovidio Gomez","twitter_card":"summary_large_image","twitter_creator":"@aduanaspanama","twitter_site":"@aduanaspanama","twitter_misc":{"Escrito por":"Ovidio Gomez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/#article","isPartOf":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/"},"author":{"name":"Ovidio Gomez","@id":"https:\/\/www.ana.gob.pa\/#\/schema\/person\/739397fec31e88f1da6069ed31320a02"},"headline":"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa","datePublished":"2026-09-01T19:37:52+00:00","dateModified":"2026-09-01T19:37:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/"},"wordCount":246,"publisher":{"@id":"https:\/\/www.ana.gob.pa\/#organization"},"image":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/09\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png","articleSection":["Ultimas Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/","url":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/","name":"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa - Autoridad Nacional de Aduanas","isPartOf":{"@id":"https:\/\/www.ana.gob.pa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/#primaryimage"},"image":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/09\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png","datePublished":"2026-09-01T19:37:52+00:00","dateModified":"2026-09-01T19:37:53+00:00","breadcrumb":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/#primaryimage","url":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/09\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png","contentUrl":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/09\/ChatGPT-Image-1-sept-2026-02_35_18-p.m.png","width":1672,"height":941},{"@type":"BreadcrumbList","@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/09\/01\/aduanas-retiene-material-explosivo-sin-documentacion-en-punto-de-control-de-divisa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ana.gob.pa\/"},{"@type":"ListItem","position":2,"name":"Aduanas retiene material explosivo sin documentaci\u00f3n en punto de control de Divisa"}]},{"@type":"WebSite","@id":"https:\/\/www.ana.gob.pa\/#website","url":"https:\/\/www.ana.gob.pa\/","name":"Autoridad Nacional de Aduanas","description":"Autoridad Nacional de Aduanas","publisher":{"@id":"https:\/\/www.ana.gob.pa\/#organization"},"alternateName":"Autoridad Nacional de Aduanas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ana.gob.pa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ana.gob.pa\/#organization","name":"Autoridad Nacional de Aduanas","alternateName":"Autoridad Nacional de Aduanas","url":"https:\/\/www.ana.gob.pa\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ana.gob.pa\/#\/schema\/logo\/image\/","url":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2025\/07\/logo-de-aduanas-y-gobierno.png","contentUrl":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2025\/07\/logo-de-aduanas-y-gobierno.png","width":2860,"height":423,"caption":"Autoridad Nacional de Aduanas"},"image":{"@id":"https:\/\/www.ana.gob.pa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aduanas.panama\/","https:\/\/x.com\/aduanaspanama","https:\/\/www.instagram.com\/aduanaspanama"]},{"@type":"Person","@id":"https:\/\/www.ana.gob.pa\/#\/schema\/person\/739397fec31e88f1da6069ed31320a02","name":"Ovidio Gomez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g","caption":"Ovidio Gomez"},"sameAs":["https:\/\/www.ana.gob.pa\/w_ana\/"],"url":"https:\/\/www.ana.gob.pa\/index.php\/author\/ogomez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/posts\/11707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/comments?post=11707"}],"version-history":[{"count":1,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/posts\/11707\/revisions"}],"predecessor-version":[{"id":11711,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/posts\/11707\/revisions\/11711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/media\/11710"}],"wp:attachment":[{"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/media?parent=11707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/categories?post=11707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/tags?post=11707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}