{"id":8447,"date":"2026-05-12T14:32:40","date_gmt":"2026-05-12T19:32:40","guid":{"rendered":"https:\/\/www.ana.gob.pa\/?p=8447"},"modified":"2026-05-12T15:30:21","modified_gmt":"2026-05-12T20:30:21","slug":"retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados","status":"publish","type":"post","link":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/","title":{"rendered":"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados"},"content":{"rendered":"\n<p>Inspectores de la Direcci\u00f3n de Prevenci\u00f3n y Fiscalizaci\u00f3n Aduanera, Zona Occidental, mediante trabajo de inteligencia e inspecci\u00f3n de local, lograron la retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol, los cuales se presume sean falsificados.<\/p>\n\n\n\n<p>El hecho se registr\u00f3 en una encomienda en Paso Canoas, muy pr\u00f3xima a la l\u00ednea fronteriza, donde se observ\u00f3 la entrada de personas con bolsas color gris, las cuales alertaron a los inspectores que se encontraban cerca del lugar, por lo que se ingres\u00f3 al lugar con un acta de inspecci\u00f3n de local. Al verificar dichas bolsas, se encontraron 73 camisetas del Mundial de Futbol que usar\u00e1 la selecci\u00f3n de Panam\u00e1, las cuales se presume que son falsificadas.<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1204\" src=\"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg\" alt=\"\" class=\"wp-image-8449\" style=\"aspect-ratio:1.3289167943837445;width:664px;height:auto\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p><br>En virtud de este hecho, se realiz\u00f3 la retenci\u00f3n y fue puesta a \u00f3rdenes de la Direcci\u00f3n de Propiedad Intelectual de Aduanas para los tr\u00e1mites correspondientes.<\/p>\n\n\n\n<p>En hechos anteriores, la Direcci\u00f3n de Propiedad Intelectual ha logrado retener su\u00e9teres de la selecci\u00f3n nacional por un valor de 200 mil balboas en perjuicio de los propietarios de la marca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inspectores de la Direcci\u00f3n de Prevenci\u00f3n y Fiscalizaci\u00f3n Aduanera, Zona Occidental, mediante trabajo de inteligencia e inspecci\u00f3n de local, lograron la retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol, los cuales se presume sean falsificados. El hecho se registr\u00f3 en una encomienda en Paso Canoas, muy pr\u00f3xima a la l\u00ednea fronteriza, donde se observ\u00f3 [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":8449,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-8447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimas-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados - Autoridad Nacional de Aduanas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados - Autoridad Nacional de Aduanas\" \/>\n<meta property=\"og:description\" content=\"Inspectores de la Direcci\u00f3n de Prevenci\u00f3n y Fiscalizaci\u00f3n Aduanera, Zona Occidental, mediante trabajo de inteligencia e inspecci\u00f3n de local, lograron la retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol, los cuales se presume sean falsificados. El hecho se registr\u00f3 en una encomienda en Paso Canoas, muy pr\u00f3xima a la l\u00ednea fronteriza, donde se observ\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/\" \/>\n<meta property=\"og:site_name\" content=\"Autoridad Nacional de Aduanas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aduanas.panama\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T19:32:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T20:30:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1204\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ovidio Gomez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aduanaspanama\" \/>\n<meta name=\"twitter:site\" content=\"@aduanaspanama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ovidio Gomez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/\"},\"author\":{\"name\":\"Ovidio Gomez\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#\\\/schema\\\/person\\\/739397fec31e88f1da6069ed31320a02\"},\"headline\":\"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados\",\"datePublished\":\"2026-05-12T19:32:40+00:00\",\"dateModified\":\"2026-05-12T20:30:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/\"},\"wordCount\":200,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg\",\"articleSection\":[\"Ultimas Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/\",\"name\":\"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados - Autoridad Nacional de Aduanas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg\",\"datePublished\":\"2026-05-12T19:32:40+00:00\",\"dateModified\":\"2026-05-12T20:30:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg\",\"width\":1600,\"height\":1204},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/2026\\\/05\\\/12\\\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ana.gob.pa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#website\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/\",\"name\":\"Autoridad Nacional de Aduanas\",\"description\":\"Autoridad Nacional de Aduanas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#organization\"},\"alternateName\":\"Autoridad Nacional de Aduanas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ana.gob.pa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#organization\",\"name\":\"Autoridad Nacional de Aduanas\",\"alternateName\":\"Autoridad Nacional de Aduanas\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-de-aduanas-y-gobierno.png\",\"contentUrl\":\"https:\\\/\\\/www.ana.gob.pa\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-de-aduanas-y-gobierno.png\",\"width\":2860,\"height\":423,\"caption\":\"Autoridad Nacional de Aduanas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aduanas.panama\\\/\",\"https:\\\/\\\/x.com\\\/aduanaspanama\",\"https:\\\/\\\/www.instagram.com\\\/aduanaspanama\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ana.gob.pa\\\/#\\\/schema\\\/person\\\/739397fec31e88f1da6069ed31320a02\",\"name\":\"Ovidio Gomez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g\",\"caption\":\"Ovidio Gomez\"},\"sameAs\":[\"https:\\\/\\\/www.ana.gob.pa\\\/w_ana\\\/\"],\"url\":\"https:\\\/\\\/www.ana.gob.pa\\\/index.php\\\/author\\\/ogomez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados - Autoridad Nacional de Aduanas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/","og_locale":"es_ES","og_type":"article","og_title":"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados - Autoridad Nacional de Aduanas","og_description":"Inspectores de la Direcci\u00f3n de Prevenci\u00f3n y Fiscalizaci\u00f3n Aduanera, Zona Occidental, mediante trabajo de inteligencia e inspecci\u00f3n de local, lograron la retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol, los cuales se presume sean falsificados. El hecho se registr\u00f3 en una encomienda en Paso Canoas, muy pr\u00f3xima a la l\u00ednea fronteriza, donde se observ\u00f3 [&hellip;]","og_url":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/","og_site_name":"Autoridad Nacional de Aduanas","article_publisher":"https:\/\/www.facebook.com\/aduanas.panama\/","article_published_time":"2026-05-12T19:32:40+00:00","article_modified_time":"2026-05-12T20:30:21+00:00","og_image":[{"width":1600,"height":1204,"url":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg","type":"image\/jpeg"}],"author":"Ovidio Gomez","twitter_card":"summary_large_image","twitter_creator":"@aduanaspanama","twitter_site":"@aduanaspanama","twitter_misc":{"Escrito por":"Ovidio Gomez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/#article","isPartOf":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/"},"author":{"name":"Ovidio Gomez","@id":"https:\/\/www.ana.gob.pa\/#\/schema\/person\/739397fec31e88f1da6069ed31320a02"},"headline":"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados","datePublished":"2026-05-12T19:32:40+00:00","dateModified":"2026-05-12T20:30:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/"},"wordCount":200,"publisher":{"@id":"https:\/\/www.ana.gob.pa\/#organization"},"image":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg","articleSection":["Ultimas Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/","url":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/","name":"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados - Autoridad Nacional de Aduanas","isPartOf":{"@id":"https:\/\/www.ana.gob.pa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/#primaryimage"},"image":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg","datePublished":"2026-05-12T19:32:40+00:00","dateModified":"2026-05-12T20:30:21+00:00","breadcrumb":{"@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/#primaryimage","url":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg","contentUrl":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-2.26.27-PM.jpeg","width":1600,"height":1204},{"@type":"BreadcrumbList","@id":"https:\/\/www.ana.gob.pa\/index.php\/2026\/05\/12\/retencion-de-sueteres-de-la-seleccion-nacional-de-futbol-presuntamente-falsificados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ana.gob.pa\/"},{"@type":"ListItem","position":2,"name":"Retenci\u00f3n de su\u00e9teres de la selecci\u00f3n nacional de futbol presuntamente falsificados"}]},{"@type":"WebSite","@id":"https:\/\/www.ana.gob.pa\/#website","url":"https:\/\/www.ana.gob.pa\/","name":"Autoridad Nacional de Aduanas","description":"Autoridad Nacional de Aduanas","publisher":{"@id":"https:\/\/www.ana.gob.pa\/#organization"},"alternateName":"Autoridad Nacional de Aduanas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ana.gob.pa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ana.gob.pa\/#organization","name":"Autoridad Nacional de Aduanas","alternateName":"Autoridad Nacional de Aduanas","url":"https:\/\/www.ana.gob.pa\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ana.gob.pa\/#\/schema\/logo\/image\/","url":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2025\/07\/logo-de-aduanas-y-gobierno.png","contentUrl":"https:\/\/www.ana.gob.pa\/wp-content\/uploads\/2025\/07\/logo-de-aduanas-y-gobierno.png","width":2860,"height":423,"caption":"Autoridad Nacional de Aduanas"},"image":{"@id":"https:\/\/www.ana.gob.pa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aduanas.panama\/","https:\/\/x.com\/aduanaspanama","https:\/\/www.instagram.com\/aduanaspanama"]},{"@type":"Person","@id":"https:\/\/www.ana.gob.pa\/#\/schema\/person\/739397fec31e88f1da6069ed31320a02","name":"Ovidio Gomez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/578eb611cee60183c01f786d1e4870e818e443ef8ae75628f2c61ac09413d3e8?s=96&d=mm&r=g","caption":"Ovidio Gomez"},"sameAs":["https:\/\/www.ana.gob.pa\/w_ana\/"],"url":"https:\/\/www.ana.gob.pa\/index.php\/author\/ogomez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/posts\/8447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/comments?post=8447"}],"version-history":[{"count":1,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/posts\/8447\/revisions"}],"predecessor-version":[{"id":8450,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/posts\/8447\/revisions\/8450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/media\/8449"}],"wp:attachment":[{"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/media?parent=8447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/categories?post=8447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ana.gob.pa\/index.php\/wp-json\/wp\/v2\/tags?post=8447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}